{"id":8,"count":30,"description":"","link":"https:\/\/citytireonline.com\/news\/archives\/category\/citytireonlinecom","name":"citytireonline.com","slug":"citytireonlinecom","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/citytireonline.com\/news\/wp-json\/wp\/v2\/categories\/8","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/citytireonline.com\/news\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/citytireonline.com\/news\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/citytireonline.com\/news\/wp-json\/wp\/v2\/posts?categories=8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}